{"id":3967,"date":"2010-08-22T14:20:36","date_gmt":"2010-08-22T12:20:36","guid":{"rendered":""},"modified":"2010-08-22T14:20:36","modified_gmt":"2010-08-22T12:20:36","slug":"3967","status":"publish","type":"post","link":"https:\/\/camerfeeling.fr.fo\/fr\/3967\/","title":{"rendered":"Les exigences de la diaspora"},"content":{"rendered":"\n\n\n<p>Apr\u00e8s la fausse note de d\u00e9part, le 1er forum \u00e9conomique et commercial avec la diaspora camerounaise, Forecdia-2010, s\u2019est achev\u00e9 samedi dernier au palais des congr\u00e8s de Yaound\u00e9, par une d\u00e9claration, appelant les autorit\u00e9s&#8230; &#8211; <\/p>\n<p>&laquo;&nbsp;Ouf&nbsp;! Plus de peur que de mal&nbsp;&raquo;, souffle l&rsquo;un des participants &agrave; ce  forum. Malgr&eacute; la cl&ocirc;ture de la phase protocolaire de la c&eacute;r&eacute;monie de  lancement de cette rencontre, la toute premi&egrave;re du genre en terre  camerounaise, il reste assis sur son si&egrave;ge et exprime son soulagement,  dans une sorte de monologue, alors que la salle se vide. C&rsquo;est que,  pr&eacute;vu le 11 ao&ucirc;t 2010, c&rsquo;est deux jours plus tard que le 1er forum  &eacute;conomique et commercial avec la diaspora camerounaise, Forecdia-2010  s&rsquo;est enfin tenu. Ce, &agrave; cause des querelles de leadership au sein du  s&eacute;rail, comme nous l&rsquo;&eacute;voquions d&eacute;j&agrave; dans l&rsquo;une de nos pr&eacute;c&eacute;dentes  &eacute;ditions. Et, finalement, malgr&eacute; la forte pr&eacute;sence des membres du  gouvernement, lors de l&rsquo;ouverture officielle, le 13 ao&ucirc;t 2010, au palais  des congr&egrave;s de Yaound&eacute;, des absences, sans explications formelles ont  &eacute;t&eacute; enregistr&eacute;es. C&rsquo;est le cas du d&eacute;l&eacute;gu&eacute; du gouvernement aupr&egrave;s de la  Communaut&eacute; urbaine de Yaound&eacute;, Gilbert Tsimi Evouna, qui devait  souhaiter la bienvenue aux participants d&egrave;s l&rsquo;entame de la c&eacute;r&eacute;monie. Il  a opt&eacute; pour la chaise vide. Tandis que le ministre des Relations  ext&eacute;rieures, Henri Eyeb&eacute; Ayissi a laiss&eacute; le ministre d&eacute;l&eacute;gu&eacute;, charg&eacute; des  Relations avec le monde islamique, Adoum Gargoum, occuper sa place. Le  Premier ministre, Yang Phil&eacute;mon, lui, a pr&eacute;f&eacute;r&eacute; se faire repr&eacute;senter par  le vice-Premier ministre, ministre de l&rsquo;Agriculture et du d&eacute;veloppement  rural, Jean Nku&eacute;t&eacute;. Un bouleversement subit dans le dispositif  protocolaire, qui a laiss&eacute; planer un vent de boycott au sommet de ce  rendez-vous pourtant tax&eacute; de haute importance par le gouvernement,  organisateur de ces assises plac&eacute;es sous le &laquo;&nbsp;tr&egrave;s haut patronage&nbsp;&raquo; du  pr&eacute;sident de la R&eacute;publique, Paul Biya.<\/p>\n<p class=\"first-child \"><strong><span title=\"D\" class=\"cap\"><span>D<\/span><\/span>iasporas de progr&egrave;s&nbsp;<\/strong><\/p>\n<p>Mais, en d&eacute;pit de ces grosses absences qui ne sont pas pass&eacute;es  inaper&ccedil;ues, Luc Magloire Mbarga Atangana n&rsquo;a pas boud&eacute; son plaisir  lorsque l&rsquo;occasion lui a enfin &eacute;t&eacute; donn&eacute;e de partager son r&ecirc;ve avec  quelque 300 participants qu&rsquo;a r&eacute;unis Forecdia-2010, dont il est le  coordonnateur. C&rsquo;est avec toute son &eacute;nergie qu&rsquo;il a martel&eacute; sa volont&eacute;  de &laquo;&nbsp;faire participer sereinement la diaspora au d&eacute;veloppement de notre  pays&nbsp;&raquo;. Surtout que, rappelle-t-il, la d&eacute;marche dans laquelle s&rsquo;engage  la Cameroun n&rsquo;est pas nouvelle. Il cite en exemples l&rsquo;Inde, la Chine, le  S&eacute;n&eacute;gal, le Mali ou le Mexique qui ont mis en &oelig;uvre des politiques  visant &agrave; amener leurs citoyens travaillant &agrave; l&rsquo;&eacute;tranger &agrave; contribuer au  d&eacute;veloppement de leurs pays d&rsquo;origine. &laquo;&nbsp;Gr&acirc;ce &agrave; leur effort &agrave;  l&rsquo;&eacute;conomie de leurs pays, ces diasporas s&rsquo;affirment comme des diasporas  de progr&egrave;s&nbsp;&raquo;, souligne Luc Magloire Mbarga Atangana, le ministre du  Commerce. Il soutient qu&rsquo;au niveau de son d&eacute;partement minist&eacute;riel, l&rsquo;on  est d&eacute;termin&eacute; &laquo;&nbsp;&agrave; assurer le service apr&egrave;s-vente et &agrave; conqu&eacute;rir des  march&eacute;s de niche, en parfaite intelligence&nbsp;&raquo; avec la diaspora  camerounaise. Pour sa part, Jean Nku&eacute;t&eacute;, s&rsquo;exprimant en lieu et place du  Premier ministre, reconna&icirc;t que &laquo;&nbsp;les Camerounais de l&rsquo;&eacute;tranger  expriment le d&eacute;sir d&rsquo;investir au Cameroun. Ils s&rsquo;int&eacute;ressent aux  programmes immobiliers et souhaitent attirer des investisseurs &eacute;trangers  et cr&eacute;er des joint-ventures. Ils s&rsquo;impliquent d&eacute;j&agrave; dans la vie  associative dans leurs pays de r&eacute;sidence et entendent faire b&eacute;n&eacute;ficier  le Cameroun des retomb&eacute;es positives de la coop&eacute;ration d&eacute;centralis&eacute;e avec  les pays amis.&nbsp;&raquo; D&rsquo;o&ugrave; sa proposition d&rsquo;un &laquo;&nbsp;partenariat  gagnant-gagnant&nbsp;&raquo; avec cette diaspora. De leur c&ocirc;t&eacute;, ces Camerounais de  l&rsquo;&eacute;tranger pensent que ce forum devrait &ecirc;tre le point de d&eacute;part pour la  mise en place d&rsquo;une plate-forme de concertation entre les pouvoirs  publics, le secteur priv&eacute; et la diaspora.<\/p>\n<p><strong>Recenser les projets<\/strong><\/p>\n<p>Dans une d&eacute;claration dite de Yaound&eacute;, les participants au  Forecdia-2010 exhortent les pouvoirs publics, entre autres&nbsp;: &agrave; acc&eacute;l&eacute;rer  la proc&eacute;dure de ratification de l&rsquo;Organisation internationale des  migrations (Oim)&nbsp;; &agrave; intensifier le processus d&rsquo;am&eacute;lioration de  l&rsquo;environnement des affaires en vue d&rsquo;attirer les investisseurs  camerounais de la diaspora et leurs partenaires&nbsp;; &agrave; mettre en place les  m&eacute;canismes permettant une meilleure canalisation de l&rsquo;&eacute;pargne de la  diaspora qui &laquo;&nbsp;peut constituer un substitut efficace &agrave; l&rsquo;aide publique  au d&eacute;veloppement, surtout en ce moment o&ugrave; s&eacute;vit fortement la crise  financi&egrave;re&nbsp;&raquo;. Ils exigent aussi la mise en place et le d&eacute;veloppement,  &laquo;&nbsp;dans les d&eacute;lais raisonnables&nbsp;&raquo;, d&rsquo;un fonds d&rsquo;investissement de la  diaspora camerounaise charg&eacute; de recenser les projets &agrave; proposer aux  migrants et, assurer le suivi de leur mise en &oelig;uvre. Cette initiative  pourrait &ecirc;tre optimis&eacute;e si elle parvient &agrave; s&rsquo;int&eacute;grer dans une dynamique  plus globale, offerte, sur le plan international, par le Fonds mondial  de la diaspora (Fmd) cr&eacute;&eacute; d&eacute;but 2010 &agrave; Gen&egrave;ve. Les participants, issus  de tous les milieux dont les administrations, le secteur priv&eacute; national,  etc. demandent la cr&eacute;ation d&rsquo;un guichet sp&eacute;cial pour les investisseurs  de la diaspora au sein de l&rsquo;agence de promotion des investissements.  Tout comme il leur faudrait des tarifications sp&eacute;ciales sur les  importations des biens d&rsquo;&eacute;quipement destin&eacute;s &agrave; la r&eacute;alisation des  projets d&rsquo;entreprises des migrants. Octroyer des exon&eacute;rations fiscales &agrave;  la diaspora au titre des projets structurants figure &eacute;galement parmi  les avantages &agrave; apporter &agrave; cette diaspora invit&eacute;e &agrave; son tour, &agrave;  mobiliser l&rsquo;&eacute;pargne en vue de sa r&eacute;injection dans l&rsquo;&eacute;conomie nationale  (transfert de fonds) et &agrave; mettre &agrave; contribution son entregent pour  attirer davantage les investissements directs &eacute;trangers, et favoriser la  cr&eacute;ation d&rsquo;entreprises au Cameroun.<\/p>\n<p>\n<span>marie.noelle.guichi<\/span><\/p>\n<p>Le Messager<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s la fausse note de d\u00e9part, le 1er forum \u00e9conomique et commercial avec la diaspora camerounaise, Forecdia-2010, s\u2019est achev\u00e9 samedi dernier au palais des congr\u00e8s de Yaound\u00e9, par une d\u00e9claration, appelant les autorit\u00e9s&#8230; &#8211; &laquo;&nbsp;Ouf&nbsp;! Plus de peur que de mal&nbsp;&raquo;, souffle l&rsquo;un des participants &agrave; ce forum. Malgr&eacute; la cl&ocirc;ture de la phase protocolaire [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"adace-sponsor":[],"class_list":["post-3967","post","type-post","status-publish","format-standard","hentry"],"acf":[],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/camerfeeling.fr.fo\/fr\/wp-json\/wp\/v2\/posts\/3967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/camerfeeling.fr.fo\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/camerfeeling.fr.fo\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/camerfeeling.fr.fo\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/camerfeeling.fr.fo\/fr\/wp-json\/wp\/v2\/comments?post=3967"}],"version-history":[{"count":0,"href":"https:\/\/camerfeeling.fr.fo\/fr\/wp-json\/wp\/v2\/posts\/3967\/revisions"}],"wp:attachment":[{"href":"https:\/\/camerfeeling.fr.fo\/fr\/wp-json\/wp\/v2\/media?parent=3967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/camerfeeling.fr.fo\/fr\/wp-json\/wp\/v2\/categories?post=3967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/camerfeeling.fr.fo\/fr\/wp-json\/wp\/v2\/tags?post=3967"},{"taxonomy":"adace-sponsor","embeddable":true,"href":"https:\/\/camerfeeling.fr.fo\/fr\/wp-json\/wp\/v2\/adace-sponsor?post=3967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}